{"id":1073,"date":"2024-07-15T10:15:45","date_gmt":"2024-07-15T08:15:45","guid":{"rendered":"https:\/\/dev-naturerholt.visual-image.de\/magazin\/?p=1073"},"modified":"2024-07-15T10:15:45","modified_gmt":"2024-07-15T08:15:45","slug":"wald-quell-des-wassers-auf-dem-wasserfallsteig-in-bad-urach","status":"publish","type":"post","link":"https:\/\/dev-naturerholt.visual-image.de\/magazin\/fr\/wald-quell-des-wassers-auf-dem-wasserfallsteig-in-bad-urach\/","title":{"rendered":"La for\u00eat. La source de l'eau : sur le sentier de la cascade \u00e0 Bad Urach"},"content":{"rendered":"<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">La for\u00eat est source d'eau et symbole de vie. Le meilleur moyen de suivre le chemin de l'eau est de parcourir l'un des cinq sentiers de randonn\u00e9e premium autour de Bad Urach : le Wasserfallsteig. Ce sentier m\u00e8ne \u00e0 la source de l'eau, la cascade de Bad Urach. Il offre en outre une vue magnifique depuis le rocher du toboggan et passe devant un autre ph\u00e9nom\u00e8ne naturel impressionnant, la chute d'eau de G\u00fcterstein.<\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"langlauf-im-heilklima-tief-durchatmen\"><strong>La chute d'eau d'Urach<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La chute d'eau d'Urach se trouve dans une r\u00e9serve naturelle et constitue un g\u00e9otope et un biotope forestier. Un ph\u00e9nom\u00e8ne particulier que l'on peut y observer est la croissance du tuf calcaire (tuf de source) : L'eau calcaire perd du calcaire au niveau des coussins de mousse, qui se d\u00e9posent et les recouvrent. Au fil des mill\u00e9naires, des d\u00e9p\u00f4ts de plusieurs m\u00e8tres d'\u00e9paisseur se sont ainsi form\u00e9s. Le tuf calcaire forme avec les mousses un habitat pr\u00e9cieux pour les insectes, qui sont \u00e0 leur tour la nourriture d'autres animaux comme la salamandre tachet\u00e9e.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"wintertage-in-st-blasien\"><strong>La chute d'eau de G\u00fcterstein<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La chute d'eau de G\u00fcterstein est plus cach\u00e9e et plus romantique, mais pas moins impressionnante que la grande chute d'eau d'Urach. L'eau tombe en cascade dans un bassin, ce qui lui donne un caract\u00e8re particulier.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"842\" src=\"https:\/\/dev-naturerholt.visual-image.de\/magazin\/wp-content\/uploads\/240711_HKM_Magazin_Bild_1_Urach-1024x842.jpg\" alt=\"\" class=\"wp-image-1079\" style=\"width:427px;height:auto\" srcset=\"https:\/\/dev-naturerholt.visual-image.de\/magazin\/wp-content\/uploads\/240711_HKM_Magazin_Bild_1_Urach-1024x842.jpg 1024w, https:\/\/dev-naturerholt.visual-image.de\/magazin\/wp-content\/uploads\/240711_HKM_Magazin_Bild_1_Urach-300x247.jpg 300w, https:\/\/dev-naturerholt.visual-image.de\/magazin\/wp-content\/uploads\/240711_HKM_Magazin_Bild_1_Urach-768x631.jpg 768w, https:\/\/dev-naturerholt.visual-image.de\/magazin\/wp-content\/uploads\/240711_HKM_Magazin_Bild_1_Urach-15x12.jpg 15w, https:\/\/dev-naturerholt.visual-image.de\/magazin\/wp-content\/uploads\/240711_HKM_Magazin_Bild_1_Urach.jpg 1276w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"wintertage-in-st-blasien\"><strong>Sentier de randonn\u00e9e Premium Wasserfallsteig<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le Wasserfallsteig, prim\u00e9 en 2016 comme le plus beau sentier de randonn\u00e9e d'Allemagne, impressionne par ses contrastes entre vall\u00e9e et plateau, for\u00eat et prairies, ombre et lumi\u00e8re ainsi que proximit\u00e9 et \u00e9loignement. La randonn\u00e9e circulaire m\u00e8ne \u00e0 travers le paysage en partie semblable \u00e0 une for\u00eat vierge de la r\u00e9serve de biosph\u00e8re du Jura souabe de l'UNESCO jusqu'\u00e0 deux chutes d'eau impressionnantes. Sur le plateau de l'Alb, on a une vue sur le Jura d'Urach et les ruines du ch\u00e2teau de Hohenurach. Ce faisant, on obtient un aper\u00e7u de la faune de la for\u00eat et on peut rendre visite aux pouliches du haras de Marbach.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"wintertage-in-st-blasien\"><strong>Itin\u00e9raire<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le Wasserfallsteig commence au parking de randonn\u00e9e Maisental P23 au pied du Schlossberg. De l\u00e0, on longe le Br\u00fchlbach dans la vall\u00e9e du m\u00eame nom, par laquelle on atteint la cascade d'Urach. Un sentier naturel avec des escaliers m\u00e8ne le long de la chute d'eau jusqu'au Hochwiese, o\u00f9 une aire de repos avec une cabane g\u00e9r\u00e9e pour la chute d'eau invite \u00e0 faire une pause. Apr\u00e8s avoir repris des forces, on monte l'Ameisenb\u00fchl en passant devant l'impressionnant rocher du toboggan. En continuant sur le haut plateau, on passe devant le refuge Rohrauer H\u00fctte et on arrive dans la for\u00eat. Un chemin forestier m\u00e8ne \u00e0 l'avant-poste Fohlenhof du haras de Marbach, o\u00f9 il y a des barbecues pour faire une pause. On emprunte un sentier en pierre naturelle \u00e0 travers la for\u00eat jusqu'\u00e0 l'ancienne chartreuse de G\u00fcterstein, on passe devant la cascade de G\u00fcterstein et on arrive au pied du versant. L\u00e0, un sentier en direction de Bad Urach permet de revenir au parking.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"wintertage-in-st-blasien\"><strong>\u00c9quipement et s\u00e9curit\u00e9<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pour le Wasserfallsteig et les autres tours du Grafensteige, il est recommand\u00e9 de porter des chaussures solides, des b\u00e2tons de marche et d'avoir le pied s\u00fbr. La roche calcaire et le sol peuvent \u00eatre tr\u00e8s glissants, en particulier apr\u00e8s et pendant les pluies et pendant les mois d'hiver.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"842\" src=\"https:\/\/dev-naturerholt.visual-image.de\/magazin\/wp-content\/uploads\/240711_HKM_Magazin_Bild_2_Urach-1024x842.jpg\" alt=\"\" class=\"wp-image-1089\" style=\"width:424px;height:auto\" srcset=\"https:\/\/dev-naturerholt.visual-image.de\/magazin\/wp-content\/uploads\/240711_HKM_Magazin_Bild_2_Urach-1024x842.jpg 1024w, https:\/\/dev-naturerholt.visual-image.de\/magazin\/wp-content\/uploads\/240711_HKM_Magazin_Bild_2_Urach-300x247.jpg 300w, https:\/\/dev-naturerholt.visual-image.de\/magazin\/wp-content\/uploads\/240711_HKM_Magazin_Bild_2_Urach-768x631.jpg 768w, https:\/\/dev-naturerholt.visual-image.de\/magazin\/wp-content\/uploads\/240711_HKM_Magazin_Bild_2_Urach-15x12.jpg 15w, https:\/\/dev-naturerholt.visual-image.de\/magazin\/wp-content\/uploads\/240711_HKM_Magazin_Bild_2_Urach.jpg 1276w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"wintertage-in-st-blasien\"><strong>Conseil apr\u00e8s la randonn\u00e9e<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L'eau peut \u00eatre poursuivie jusqu'aux Alb Thermen Bad Urach apr\u00e8s une randonn\u00e9e fatigante. L\u00e0, le corps et l'esprit peuvent se d\u00e9tendre dans six bassins int\u00e9rieurs et ext\u00e9rieurs d'une eau chauff\u00e9e entre 32 et 38 degr\u00e9s ou profiter de la chaleur bienfaisante de l'espace sauna. Depuis plus de 150 ans, Bad Urach est connue comme une anomalie g\u00e9ologique. Les scientifiques soup\u00e7onnaient la pr\u00e9sence d'eau min\u00e9rale hyperthermale \u00e0 grande profondeur. En 1969, des citoyens locaux ont fond\u00e9 la \"soci\u00e9t\u00e9 de forage de la vall\u00e9e de l'Erm\" et ont d\u00e9couvert en 1970, \u00e0 770 m\u00e8tres de profondeur, de l'eau de source chaude, l'eau thermale actuelle.<\/p>\n\n\n\n<div style=\"height:64px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h5 class=\"wp-block-heading\">R\u00e9f\u00e9rences<\/h5>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\" style=\"letter-spacing:0px\"><a href=\"https:\/\/www.badurach-tourismus.de\/tour\/wasserfallsteig-694f35807b\">https:\/\/www.badurach-tourismus.de\/<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Der Wald ist Quell des Wassers und Symbol des Lebens. Den Weg des Wassers kann man am besten auf einem der f\u00fcnf Premiumwanderwege rund um Bad Urach verfolgen: dem Wasserfallsteig. Der Weg f\u00fchrt zum Ursprung des Wassers, dem Bad Uracher Wasserfall. Zudem bietet er einen herrlichen Ausblick vom Rutschenfelsen und f\u00fchrt an einem weiteren beeindruckenden [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1092,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[9,8,6,10,7],"class_list":["post-1073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-baden-wuerttemberg","tag-schwarzwald","tag-terpene","tag-wald","tag-waldbaden"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev-naturerholt.visual-image.de\/magazin\/fr\/wp-json\/wp\/v2\/posts\/1073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev-naturerholt.visual-image.de\/magazin\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev-naturerholt.visual-image.de\/magazin\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev-naturerholt.visual-image.de\/magazin\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dev-naturerholt.visual-image.de\/magazin\/fr\/wp-json\/wp\/v2\/comments?post=1073"}],"version-history":[{"count":22,"href":"https:\/\/dev-naturerholt.visual-image.de\/magazin\/fr\/wp-json\/wp\/v2\/posts\/1073\/revisions"}],"predecessor-version":[{"id":1099,"href":"https:\/\/dev-naturerholt.visual-image.de\/magazin\/fr\/wp-json\/wp\/v2\/posts\/1073\/revisions\/1099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev-naturerholt.visual-image.de\/magazin\/fr\/wp-json\/wp\/v2\/media\/1092"}],"wp:attachment":[{"href":"https:\/\/dev-naturerholt.visual-image.de\/magazin\/fr\/wp-json\/wp\/v2\/media?parent=1073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev-naturerholt.visual-image.de\/magazin\/fr\/wp-json\/wp\/v2\/categories?post=1073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev-naturerholt.visual-image.de\/magazin\/fr\/wp-json\/wp\/v2\/tags?post=1073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}